{"id":9808,"date":"2024-02-16T22:00:00","date_gmt":"2024-02-17T04:00:00","guid":{"rendered":"https:\/\/cronicadesoledad.com\/?p=9808"},"modified":"2024-02-16T22:10:52","modified_gmt":"2024-02-17T04:10:52","slug":"presentan-playera-y-medalla-de-la-carrera-atletica-de-la-enchilada","status":"publish","type":"post","link":"https:\/\/cronicadesoledad.com\/index.php\/2024\/02\/16\/presentan-playera-y-medalla-de-la-carrera-atletica-de-la-enchilada\/","title":{"rendered":"Presentan playera y medalla de la Carrera Atl\u00e9tica de la Enchilada"},"content":{"rendered":"\n<p>En el Teatro y Centro Cultural \u201cDoroteo Arango\u201d de Soledad de Graciano S\u00e1nchez, autoridades municipales, encabezadas por la Alcaldesa, Leonor Noyola Cervantes, presentaron oficialmente el kit deportivo que se entregar\u00e1 a las y los participantes de la Carrera Atl\u00e9tica de la Enchilada novena edici\u00f3n, que incluye playera, medalla, cilindro, hidratante, pack y gorra; como parte de las actividades que engalanan la Feria Nacional de la Enchilada (FENAE) 2024. Este a\u00f1o, la lid contempla una bolsa a repartir en premios de m\u00e1s de 300 mil pesos.<\/p>\n\n\n\n<p>La Carrera Atl\u00e9tica de la Enchilada se llevar\u00e1 a cabo el pr\u00f3ximo domingo 24 de marzo, y tendr\u00e1 una distancia para la competencia principal de 10 kil\u00f3metros para aquellos que buscan poner a prueba su resistencia y velocidad, as\u00ed como un trayecto de 3 kil\u00f3metros pensado a la recreaci\u00f3n y convivencia familiar; tambi\u00e9n, se ofrece categor\u00edas tanto en la rama varonil como femenil y, por supuesto, la categor\u00eda especial para sillas de ruedas, reiterando el compromiso inclusivo del evento.<\/p>\n\n\n\n<p>Asimismo, se detallaron las rutas, donde las y los atletas de los 10K partir\u00e1n desde la Plaza principal de Soledad, atravesar\u00e1n la Calle Benito Ju\u00e1rez, tomar\u00e1n la lateral de carretera a Matehuala, seguir\u00e1n por las avenidas Soledad y Acceso Norte, cruzar\u00e1n la avenida San Pedro, retornar\u00e1n por la lateral de carretera a Matehuala y concluir\u00e1n en la Calle Hidalgo hasta llegar nuevamente al punto de partida.<\/p>\n\n\n\n<p>En cambio, las y los participantes de la carrera familiar disfrutar\u00e1n de un recorrido m\u00e1s corto, pero igualmente emblem\u00e1tico por las calles principales de la ciudad, donde adem\u00e1s podr\u00e1n participar desde ni\u00f1as y ni\u00f1os hasta personas de la tercera edad, a la par ser\u00e1n les entregar\u00e1 un reconocimiento especial a las y los mejores corredores de esta competencia.<\/p>\n\n\n\n<p>Durante la presentaci\u00f3n, la Alcaldesa Leonor Noyola Cervantes comparti\u00f3 palabras de aliento y expectaci\u00f3n: &#8220;el a\u00f1o pasado disfrutamos de la energ\u00eda de casi tres mil participantes, este a\u00f1o, apuntamos m\u00e1s alto, esperando superar esa cifra y convocar a atletas de todas latitudes en un evento que resalta la importancia de la salud y la felicidad&#8221;.<\/p>\n\n\n\n<p>Hizo hincapi\u00e9 en la amplia oferta de la FENAE 2024, destacando los actos musicales programados con artistas como Molotov, El Tri, Ana B\u00e1rbara, Los Acosta, La Fiera de Ojinaga, Laberinto, y el m\u00e1s reciente agregado a la lista, Gabito Ballesteros, reafirmando que la carrera es solo el inicio de una festividad que celebra la cultura, tradici\u00f3n y deportividad.<\/p>\n\n\n\n<p>Las inscripciones ya est\u00e1n abiertas con un costo de 200 pesos, disponibles en la Presidencia municipal, la Coordinaci\u00f3n Municipal de Deportes, el Centro de Alto Rendimiento \u201cPlan de San Luis\u201d y otros espacios gestionados por \u201cTu Tiempo a Tiempo\u201d.<\/p>\n\n\n\n<p>Acompa\u00f1aron a las autoridades de Soledad de Graciano S\u00e1nchez, integradas por el secretario General del Ayuntamiento, Ernesto Jes\u00fas Barajas \u00c1brego; el Oficial Mayor, Alejandro Serrano Cort\u00e9s; el titular de Deportes, Hugo Esquivel Montoya; el representante de la empresa \u201cTu Tiempo a Tiempo\u201d, Jos\u00e9 Luis Garc\u00eda y la ganadora de ediciones anteriores, Rosa Mar\u00eda P\u00e9rez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Teatro y Centro Cultural \u201cDoroteo Arango\u201d de Soledad de Graciano S\u00e1nchez, autoridades municipales, encabezadas por la Alcaldesa, Leonor Noyola Cervantes, presentaron oficialmente el kit deportivo que se entregar\u00e1 a las y los participantes de la Carrera Atl\u00e9tica de la Enchilada novena edici\u00f3n, que incluye playera, medalla, cilindro, hidratante, pack y gorra; como parte [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,1,24,21],"tags":[81,223,500,1596,321,271,1635,1473,1472,1658,29,294,261,27],"class_list":{"0":"post-9808","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cronica-deportiva","8":"category-destacadas","9":"category-informacion-general","10":"category-tu-soledad","11":"tag-alcaldesa-soledense","12":"tag-ayuntamiento-soledense","13":"tag-carrera","14":"tag-carrera-atletica-de-la-enchilada","15":"tag-cronica-deportiva","16":"tag-deporte","17":"tag-fenae","18":"tag-fenae-2024","19":"tag-feria-nacional-de-la-enchilada","20":"tag-feria-nacional-de-la-enchilada-2024","21":"tag-leonor-noyola","22":"tag-san-luis","23":"tag-slp","24":"tag-soledad"},"_links":{"self":[{"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/posts\/9808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/comments?post=9808"}],"version-history":[{"count":1,"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/posts\/9808\/revisions"}],"predecessor-version":[{"id":9810,"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/posts\/9808\/revisions\/9810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/media\/9809"}],"wp:attachment":[{"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/media?parent=9808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/categories?post=9808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cronicadesoledad.com\/index.php\/wp-json\/wp\/v2\/tags?post=9808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}